{"id":2285,"date":"2019-07-26T18:20:19","date_gmt":"2019-07-26T17:20:19","guid":{"rendered":"http:\/\/www.gruposcoutphoenix.com\/blog\/?p=2285"},"modified":"2019-07-26T21:43:27","modified_gmt":"2019-07-26T20:43:27","slug":"dia-10-25-julio-puentenansa-2019","status":"publish","type":"post","link":"http:\/\/www.gruposcoutphoenix.com\/blog\/dia-10-25-julio-puentenansa-2019\/","title":{"rendered":"D\u00eda 10 (25 julio) Puentenansa 2019"},"content":{"rendered":"\n<p>Que den comienzo los Juegos del Hambre.<br> As\u00ed empieza el d\u00eda para la Tropa Scout. Dividida en distritos deben procurar su subsistencia en el campamento.<br> En el centro del campa se monta la Cornucopia donde se colocan los suministros, armas y enseres que deben agenciarse.<\/p>\n\n\n\n<p>Los distritos tambi\u00e9n pueden conseguir patrocinio de personas del campa para obtener comida, ropa y otros suministros para sobrevivir, ademas de poder ir al pueblo cercano a procurarse estos elementos para pasar estas horas sin mucha penuria.<br> Un juego apasionante que se toman muy en serio y lo disfrutan.<\/p>\n\n\n\n<p>El d\u00eda ha amanecido nublado pero no por mucho tiempo, pues hemos vuelto a pasar calor y a poder paliarlo con nuestro querido r\u00edo.<\/p>\n\n\n\n<p>La Unidad Esculta ha tenido una din\u00e1mica de dilemas morales. Un taller interesante en el que han podido hablar sobre temas de la vida cotidiana, laborales y sociales que llevan a plantearnos dudas sobre las costumbres y usos de la sociedad actual.<\/p>\n\n\n\n<p>Esta tarde ha habido Consejos en las secciones, alg\u00fan taller de cocina (tartas) etc.<\/p>\n\n\n\n<p>Muchos juegos, actividades como te\u00f1ir camisetas y otras din\u00e1micas preparadas desde Madrid por los propios chavales han cubierto el d\u00eda.<\/p>\n\n\n\n<p>Cubierto tambi\u00e9n ha aparecido  el cielo a \u00faltima hora de la tarde empezando a llover de nuevo.<\/p>\n\n\n\n<p>Hemos disfrutado de unas lentejas brutales de plato \u00fanico (vegetarianas y no vegetarianas)<br> Para cenar los esperad\u00edsimos filetes rusos con salsa de tomate casera caser\u00edsima y arroz. <\/p>\n\n\n\n<p>Escondidos bajos las carpas de nuevo por la tormenta todos juegan y cantan.<br>\nNos vamos al saco con ganas de que escampe pronto.<\/p>\n\n\n\n<p>Buenas noches y buena caza.<\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-10-25-julio-puentenansa-2019%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2285\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 10 (25 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-10-25-julio-puentenansa-2019%2F&text=Nuevo+post%3A+D%C3%ADa+10+%2825+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2285\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 10 (25 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-10-25-julio-puentenansa-2019%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2285\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 10 (25 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Que den comienzo los Juegos del Hambre. As\u00ed empieza el d\u00eda para la Tropa Scout. Dividida en distritos deben procurar su subsistencia en el campamento. En el centro del campa se monta la Cornucopia donde se colocan los suministros, armas y enseres que deben agenciarse. Los distritos tambi\u00e9n pueden conseguir patrocinio de personas del campa [&hellip;]<\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-10-25-julio-puentenansa-2019%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2285\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 10 (25 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-10-25-julio-puentenansa-2019%2F&text=Nuevo+post%3A+D%C3%ADa+10+%2825+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2285\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 10 (25 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-10-25-julio-puentenansa-2019%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2285\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 10 (25 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"author":49,"featured_media":2288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2285"}],"collection":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/comments?post=2285"}],"version-history":[{"count":3,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2285\/revisions"}],"predecessor-version":[{"id":2289,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2285\/revisions\/2289"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media\/2288"}],"wp:attachment":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media?parent=2285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/categories?post=2285"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/tags?post=2285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}