{"id":2264,"date":"2019-07-23T21:52:28","date_gmt":"2019-07-23T20:52:28","guid":{"rendered":"http:\/\/www.gruposcoutphoenix.com\/blog\/?p=2264"},"modified":"2019-07-26T21:43:53","modified_gmt":"2019-07-26T20:43:53","slug":"dia-7-22-julio-puentenansa-2019","status":"publish","type":"post","link":"http:\/\/www.gruposcoutphoenix.com\/blog\/dia-7-22-julio-puentenansa-2019\/","title":{"rendered":"D\u00eda 7 (22 julio) Puentenansa 2019"},"content":{"rendered":"\n<p>Buenos d\u00edas Familia Scout.<br>Hoy es d\u00eda de colada. La ropa limpia se nos va acabando y debemos aprender a lavarla en el campo.<br>Con barre\u00f1os, jab\u00f3n lagarto y nuestras manos, los castores, frota que te frota, sacamos \u201cun poquito\u201d la ro\u00f1a de las camisetas que antes eran blancas. A nuestros padres se les saltar\u00e1n las lagrimas, seguro, esperando que  tambi\u00e9n lo hagamos en casa al finalizar el campamento.<br>Despu\u00e9s hemos tenido un taller sobre lo importante que es la promesa Castor si quremos ser buenos Scouts en el futuro. Nuestra tem\u00e1tica de hoy ha sido el circo, con actividades y juegos relacionadas con ello.<br>El d\u00eda amanece nublado, pero parece que va a abrir a prop\u00f3sito, para secar la ropa. (ya veremos).<\/p>\n\n\n\n<p>El Clan nos ha sorprendido llegando de su ruta a las 7 de la ma\u00f1ana.<br>Su \u00faltima etapa ha sido nocturna. Han comenzado a andar a las 5 de la madrugada. Estas marchas por la noche, con luna, son realmente para recordar. <br>Al llegar se han metido a las duchas directamente (c\u00f3mo llegar\u00edan!!!)). <br>Toda la ruta (seis d\u00edas con sus cinco noches) ha sido realmente dura, pero algo tienen que graba historias imborrables.<\/p>\n\n\n\n<p>El resto del grupo tambi\u00e9n hace su colada para luego continuar con sus actividades. La Campa est\u00e1 ahora repleta de scouts peque\u00f1os y muy peque\u00f1os, grandes y muy grandes. Estamos todos.<br>Hoy se nos ha incorporado una nueva monitora en pr\u00e1cticas,  ademas de la ayuda de una Scouter del Grupo San Viator (amigos del Phoenix), Elvira,  que ayudar\u00e1 en la cocina esta \u00faltima semana.<\/p>\n\n\n\n<p>Tambi\u00e9n llega Javier. Nueva incorporaci\u00f3n al Refugio (al menos para este campamento). Llega con ganas de aprender y con una sonrisa de oreja a oreja. <br><\/p>\n\n\n\n<p>Unos macarrones con picadillo de carne hacen las delicias de los paladares exigentes y hambrientos, y para cenar, el panadero del pueblo nos ha asado dos piernas de cerdo que ya las pillara Carpanta.<\/p>\n\n\n\n<p>Como se pod\u00eda prever el tiempo se nos ha complicado un poco esta noche y despu\u00e9s de cenar hemos tenido una buena tormenta el\u00e9ctrica con lluvia fuerte algunos minutos. Para los chavales (y no tan chavales) ha sido una experiencia. Todos metidos en la carpa grande con nuestros chubasqueros bailando y cantando animados por los Scouter (Qu\u00e9 bien lo saben hacer en estos casos).<\/p>\n\n\n\n<p>Nos vamos a dormir. Esperemos que ma\u00f1ana la tormenta no nos deje muchos da\u00f1os que reparar.<br>Buenas noches y Buena Caza<\/p>\n\n\n\n<p>Enlace a fotos: https:\/\/photos.app.goo.gl\/g7vTeyTf64t5W95s6<\/p>\n\n\n\n<p><\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-7-22-julio-puentenansa-2019%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2264\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 7 (22 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-7-22-julio-puentenansa-2019%2F&text=Nuevo+post%3A+D%C3%ADa+7+%2822+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2264\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 7 (22 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-7-22-julio-puentenansa-2019%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2264\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 7 (22 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas Familia Scout.Hoy es d\u00eda de colada. La ropa limpia se nos va acabando y debemos aprender a lavarla en el campo.Con barre\u00f1os, jab\u00f3n lagarto y nuestras manos, los castores, frota que te frota, sacamos \u201cun poquito\u201d la ro\u00f1a de las camisetas que antes eran blancas. A nuestros padres se les saltar\u00e1n las lagrimas, [&hellip;]<\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-7-22-julio-puentenansa-2019%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2264\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 7 (22 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-7-22-julio-puentenansa-2019%2F&text=Nuevo+post%3A+D%C3%ADa+7+%2822+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2264\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 7 (22 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-7-22-julio-puentenansa-2019%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2264\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 7 (22 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"author":49,"featured_media":2270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2264"}],"collection":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/comments?post=2264"}],"version-history":[{"count":7,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2264\/revisions"}],"predecessor-version":[{"id":2295,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2264\/revisions\/2295"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media\/2270"}],"wp:attachment":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media?parent=2264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/categories?post=2264"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/tags?post=2264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}