{"id":2256,"date":"2019-07-22T12:31:09","date_gmt":"2019-07-22T11:31:09","guid":{"rendered":"http:\/\/www.gruposcoutphoenix.com\/blog\/?p=2256"},"modified":"2019-07-23T21:28:11","modified_gmt":"2019-07-23T20:28:11","slug":"__trashed-3","status":"publish","type":"post","link":"http:\/\/www.gruposcoutphoenix.com\/blog\/__trashed-3\/","title":{"rendered":"D\u00eda 6 (21 julio) Puentenansa 2019"},"content":{"rendered":"\n<p>Hoy, como anunciaron, amanece el d\u00eda nublado y fresco, lo que se agradece tras el calor sofocante de los d\u00edas pasados.<\/p>\n\n\n\n<p>La Colonia, durante la ma\u00f1ana, toman la cocina para elaborar una tarta de rechupete, de la que daremos buena cuenta algunos privilegiados a la hora de la merienda. Por la tarde juegan, sudan, r\u00eden y se divierten.<\/p>\n\n\n\n<p>La Manada aprende jugando: han experimentado la fuerza de la naturaleza preparando un volc\u00e1n de bicarbonato, y desfogan sus energ\u00edas con juegos como el \u00abBote Botero\u00bb y \u00abPi\u00bb<\/p>\n\n\n\n<p>Tropa durante el d\u00eda ha estado realizando diferentes actividades preparadas por ellos, todas ellas basadas en el desarrollo sostenible. <\/p>\n\n\n\n<p>Men\u00fa del d\u00eda: Comida, arroz caldoso con chipirones.<br>                          Cena, jud\u00edas verdes con tomate y chuleta de Sajonia.<\/p>\n\n\n\n<p>Y a continuaci\u00f3n las gacetillas de los que andan fuera:<\/p>\n\n\n\n<p>Esculta: <em>Nos despedimos de la playa de San Vicente y partimos hacia Cades, punto clave en el camino Lebaniego. La ruta fue mucho m\u00e1s liviana que el resto de d\u00edas pero con chispeo constante, el tiempo no acompa\u00f1aba. Al llegar a Cades la esculta cocin\u00f3 un estupendo arroz con tomate, ma\u00edz y at\u00fan y tras la siesta nos movimos los \u00faltimos kil\u00f3metros por carretera para visitar al clan vecino en Celis, donde hicimos algo de yoga para estirar bien todo el cuerpo. Cenamos, nos comimos un helado y \u00a1a dormir!<\/em><\/p>\n\n\n\n<p>Clan: <em> 21 de julio 1936: Durante la noche de ayer salieron por primera vez a la carga, una nueva era de h\u00e9roes y hero\u00ednas, el Clan antiara\u00f1as. Con nuestras armas (dos cacerolas) luchamos contra el Octopus, tras un taconeo y un RKO, acabamos haciendo una trinchera de macutos. <\/em><br><em>Esta ma\u00f1anuca, recibimos un comunicado de Miguel Hern\u00e1ndez, necesitaba que construy\u00e9ramos un refugio, un escondite subterr\u00e1neo y una flor de lis visible a 100 metros. <br>Tras cumplir las misiones, nos dirigimos a la Cueva El Soplao. Nos subimos en el trenecito para conocer la maravillosa creaci\u00f3n de la naturaleza, aprovechada por los maquis  conocidos como Juan\u00edn y Bedoya,<\/em><br><em>como escondite . En 1857, al igual que el nacimiento de Baden Powell, se inici\u00f3 la apertura de esta cueva, la cual se quer\u00eda aprovechar para la extracci\u00f3n de Zinc y Plomo. Tras muchas estalactitas y estalagmitas, llegamos a la sala de la \u00d3pera donde nos dejamos el cuello mirando el indescriptible techo. <br>Despu\u00e9s un rico bocata de sardinas con las vistas a nuestro siguiente objetivo, Celis. David y Candela de camino a la escuela han escuchado una buen historia sobre la Guerra Civil. Hemos visita al grupo Scout Pl\u00e9yades de Salamanca, que ten\u00edan d\u00eda de familias. Mientras hac\u00edamos la cena ha llegado la Esculta, unas m\u00e1quinas de andar. Tras los saludos protocolarios, hemos jugado la \u00faltima partida de gatitos durante la ruta, en la que Luc\u00eda, como siempre, perdi\u00f3 la primera ronda. Ma\u00f1ana madrug\u00f3n. Buenas noches.<br>Frase del d\u00eda: \u00abEn vuestra mano est\u00e1 la libertad del ala, la libertad del mundo, soldados voladores: y arrancar\u00e9is del cielo la codiciosa y mala hierba de otros motores\u00bb (Miguel Hern\u00e1ndez)<\/em><\/p>\n\n\n\n<p>Y con esto y un bizcocho&#8230;hasta ma\u00f1ana a las ocho!!!<\/p>\n\n\n\n<p>Buenas noches y buena caza!!<\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2F__trashed-3%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2256\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 6 (21 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2F__trashed-3%2F&text=Nuevo+post%3A+D%C3%ADa+6+%2821+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2256\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 6 (21 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2F__trashed-3%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2256\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 6 (21 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Hoy, como anunciaron, amanece el d\u00eda nublado y fresco, lo que se agradece tras el calor sofocante de los d\u00edas pasados. La Colonia, durante la ma\u00f1ana, toman la cocina para elaborar una tarta de rechupete, de la que daremos buena cuenta algunos privilegiados a la hora de la merienda. Por la tarde juegan, sudan, r\u00eden [&hellip;]<\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2F__trashed-3%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2256\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 6 (21 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2F__trashed-3%2F&text=Nuevo+post%3A+D%C3%ADa+6+%2821+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2256\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 6 (21 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2F__trashed-3%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2256\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 6 (21 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"author":49,"featured_media":2257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2256"}],"collection":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/comments?post=2256"}],"version-history":[{"count":6,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2256\/revisions"}],"predecessor-version":[{"id":2263,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2256\/revisions\/2263"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media\/2257"}],"wp:attachment":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media?parent=2256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/categories?post=2256"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/tags?post=2256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}