{"id":2231,"date":"2019-07-20T22:13:51","date_gmt":"2019-07-20T21:13:51","guid":{"rendered":"http:\/\/www.gruposcoutphoenix.com\/blog\/?p=2231"},"modified":"2019-07-21T09:27:34","modified_gmt":"2019-07-21T08:27:34","slug":"dia-5-20-julio-puentenansa-2019","status":"publish","type":"post","link":"http:\/\/www.gruposcoutphoenix.com\/blog\/dia-5-20-julio-puentenansa-2019\/","title":{"rendered":"D\u00eda 5 (20 julio) Puentenansa 2019"},"content":{"rendered":"\n<p>Hoy s\u00e1bado, nuestros castores, lobatos y troperos vuelven a casa!!<\/p>\n\n\n\n<p>Les esperan unas lentejitas reci\u00e9n hechas de las que dar\u00e1n buena cuenta (ver testimonio gr\u00e1fico)<\/p>\n\n\n\n<p>A las 12 empiezan a entrar los castores, seguidos muy de cerca por la manada. Nada m\u00e1s llegar a la campa, sueltan sus macutos para darse un reconfortante ba\u00f1o en el r\u00edo, y, a continuaci\u00f3n la no menos esperada (sobre todo para los que les rodean) ducha.<\/p>\n\n\n\n<p>Poco m\u00e1s tarde los troperos, tras una preciosa caminata de 10 km desde Quintanilla, hacen su gran entrada, y ellos ingresan directamente en las duchas, pasando algunas por un improvisado sal\u00f3n de belleza (ver testimonio gr\u00e1fico)<\/p>\n\n\n\n<p>Tras las lentejas, el cielo ha comenzado a cubrirse y durante toda la tarde hemos tenido un txirimiri, calabobos u orballo, que nos ha dado un poquito de descanso del agotador calor de estos d\u00edas. Las actividades han sido a cubierto pero no por ello sin contenido educativo y sobre todo divertidas. Desde un especial juego del pa\u00f1uelo con preguntas de todo tipo a un entretenido HeadsUp (qu\u00e9 tengo en el coco).<br>Consejos de problemas los Castores.<br>En el Refugio se han \u00abboleado\u00bb 266 alb\u00f3ndigas con una salsa espectacular.<br>No os podemos dejar muestra de los restos porque no ha quedado ni para guardar la que nos obliga Sanidad.<br>Tranquilos que los \u00abvegasupralacteopsicopisciovovegetarianos\u00bb tambi\u00e9n han disfrutado de lo lindo. <\/p>\n\n\n\n<p>Y, por su lado, nuestros mayores nos env\u00edan sus noticias:<\/p>\n\n\n\n<p><strong>Esculta<\/strong>: <em>Hoy hemos tenido nuestro s\u00faper d\u00eda de descanso en la ruta!! Cogimos bus por la ma\u00f1ana en Potes para ir a San Vicente de la Barquera, uno de los pueblos m\u00e1s bonicos de Espa\u00f1a. All\u00ed hemos subido al Faro de apunta Silla donde nos esperaba Jes\u00fas Garz\u00f3n, presidente de la asociaci\u00f3n de trashumancia en nuestro pa\u00eds e impulsor del Parque de Oyambre, quien nos ha acompa\u00f1ado por la ma\u00f1ana y nos ha ayudado a llevar nuestros macutos al camping en la playa, maaaassss majo!!<\/em><br><em>Despu\u00e9s hemos pasado toooda la tarde en la playa, descansando nuestros pies y d\u00e1ndonos un chapuz\u00f3n necesario! Por la noche la esculta ha cenado de sorpresa con su dinero del proyecto \u00a1\u00a1en una pizzer\u00eda!!<br><\/em><br><\/p>\n\n\n\n<p><strong>Clan<\/strong>:<em> 20 de julio de 1936<br>Como cada d\u00eda, nos despertamos a las 6:00, para aprovechar las horas nocturnas. Esta ma\u00f1anuca comienza la esperada Supervivencia. Nos ha llegado una carta urgente del Ministerio del Tiempo. Miguel Hern\u00e1ndez nos pide ayuda desde 1936, \u00e9poca importante en la historia de Espa\u00f1a. Un m\u00e9dico, un soldado raso, un artista, una ingeniera, un ni\u00f1o y un detector de minas han surcado largas colinas para cumplir las misiones requeridas. Durante el trayecto, los Rovers han recopilado informaci\u00f3n sobre la Guerra Civil en los pueblos por los que han ido pasando el dia de hoy.<br>En un alto durante nuestro camino, el se\u00f1or m\u00e1s mayor y en forma que hemos conocido en nuestra vida, nos ha regalado limones, mientras disfrut\u00e1bamos de una rica mediama\u00f1ana de mel\u00f3n con chocolate. Al llegar a Bielva nos han ofrecido comida, ducha, alojamiento,\u2026 pero hemos decidido quedarnos en un cuco techadito que pegaba con nuestro estilo de vida. Una rica siesta despu\u00e9s de una buena fabada no pod\u00eda faltar, adem\u00e1s de disfrutar de un partido de f\u00fatbol en primera fila.<br>Seguimos progresando para que la l\u00ednea temporal siga su camino. Ma\u00f1ana recibiremos nuevas cartas con sus consecuentes misiones. El pasado, presente y futuro, est\u00e1 en nuestras manos.<br>Concluimos el d\u00eda con unos buenos chupitos de leche condensada y unas partidas con \u00abGloria a la BSK\u00bb.<br>Frase del d\u00eda: \u00abUna gota de pura valent\u00eda vale m\u00e1s que un oc\u00e9ano cobarde\u00bb Miguel Hern\u00e1ndez<\/em><\/p>\n\n\n\n<p>Sin m\u00e1s que a\u00f1adir, nos retiramos esperando que ma\u00f1ana se cumpla la previsi\u00f3n de tiempo suave y nublado.<\/p>\n\n\n\n<p>Buenas noches y buena caza!!<\/p>\n\n\n\n<p>Enlace a fotos: <a href=\"https:\/\/photos.app.goo.gl\/g7vTeyTf64t5W95s6\">https:\/\/photos.app.goo.gl\/g7vTeyTf64t5W95s6<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p> <\/p>\n\n\n\n<p><\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-5-20-julio-puentenansa-2019%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2231\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 5 (20 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-5-20-julio-puentenansa-2019%2F&text=Nuevo+post%3A+D%C3%ADa+5+%2820+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2231\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 5 (20 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-5-20-julio-puentenansa-2019%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2231\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 5 (20 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Hoy s\u00e1bado, nuestros castores, lobatos y troperos vuelven a casa!! Les esperan unas lentejitas reci\u00e9n hechas de las que dar\u00e1n buena cuenta (ver testimonio gr\u00e1fico) A las 12 empiezan a entrar los castores, seguidos muy de cerca por la manada. Nada m\u00e1s llegar a la campa, sueltan sus macutos para darse un reconfortante ba\u00f1o en [&hellip;]<\/p>\n<div data-animation=\"no-animation\" data-icons-animation=\"no-animation\" data-overlay=\"\" data-change-size=\"\" data-button-size=\"1\" style=\"font-size:1em!important;display:none;\" class=\"supsystic-social-sharing supsystic-social-sharing-package-flat supsystic-social-sharing-content supsystic-social-sharing-content-align-center\" data-text=\"\"><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter facebook\" target=\"_blank\" title=\"Facebook\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-5-20-julio-puentenansa-2019%2F\" data-main-href=\"http:\/\/www.facebook.com\/sharer.php?u={url}\" data-nid=\"1\" data-name=\"\" data-pid=\"1\" data-post-id=\"2231\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 5 (20 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-facebook\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">119<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter twitter\" target=\"_blank\" title=\"Twitter\" href=\"https:\/\/twitter.com\/share?url=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-5-20-julio-puentenansa-2019%2F&text=Nuevo+post%3A+D%C3%ADa+5+%2820+julio%29+Puentenansa+2019\" data-main-href=\"https:\/\/twitter.com\/share?url={url}&text={title}\" data-nid=\"2\" data-name=\"\" data-pid=\"1\" data-post-id=\"2231\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 5 (20 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-twitter\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">34<\/span><\/div><\/a><a data-networks=\"[]\" class=\"social-sharing-button sharer-flat sharer-flat-5 counter-standard without-counter whatsapp\" target=\"_blank\" title=\"WhatsApp\" href=\"https:\/\/web.whatsapp.com\/send?text=http%3A%2F%2Fwww.gruposcoutphoenix.com%2Fblog%2Fdia-5-20-julio-puentenansa-2019%2F\" data-main-href=\"https:\/\/web.whatsapp.com\/send?text={url}\" data-nid=\"18\" data-name=\"\" data-pid=\"1\" data-post-id=\"2231\" data-url=\"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-admin\/admin-ajax.php\" data-description=\"D\u00eda 5 (20 julio) Puentenansa 2019\" rel=\"nofollow\" data-mailto=\"\"><i class=\"fa-ssbs fa-ssbs-fw fa-ssbs-whatsapp\"><\/i><div class=\"counter-wrap standard\"><span class=\"counter\">113<\/span><\/div><\/a><\/div>","protected":false},"author":49,"featured_media":2254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2231"}],"collection":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/comments?post=2231"}],"version-history":[{"count":9,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2231\/revisions"}],"predecessor-version":[{"id":2253,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/posts\/2231\/revisions\/2253"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media\/2254"}],"wp:attachment":[{"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/media?parent=2231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/categories?post=2231"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.gruposcoutphoenix.com\/blog\/wp-json\/wp\/v2\/tags?post=2231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}